{"id":4414,"date":"2014-09-06T16:38:01","date_gmt":"2014-09-06T15:38:01","guid":{"rendered":"https:\/\/www.bonberenea.com\/?post_type=product&#038;p=4414"},"modified":"2016-04-16T22:27:40","modified_gmt":"2016-04-16T21:27:40","slug":"kklrd","status":"publish","type":"product","link":"https:\/\/www.bonberenea.com\/es\/online-denda\/kklrd\/","title":{"rendered":"KKLRD"},"content":{"rendered":"<p>Ya esta en la calle KKLRD!! el trabajo es fruto de la colaboracion de diferentes artistas: ZINC, ESTRICALLA, HUMILITATE, MOSTROS, JOSEVISKY y BONBERENEA EKINTZAK. Mezcla de musica y el arte del comic. Una cancion inedita por cada banda en formato EP+CD con comic y todo de la mano de Bonberenea ekintzak.<\/p>\n<p style=\"text-align: center;\"><iframe src=\"\/\/player.vimeo.com\/video\/39722212\" width=\"500\" height=\"281\" frameborder=\"0\" title=\"KKLRD split EP+CD+Comic!\" webkitallowfullscreen mozallowfullscreen allowfullscreen><\/iframe><\/p>\n<p><strong>Contacto:<\/strong><\/p>\n<p><a href=\"myspace.com\/zincmyspace\">myspace.com\/zincmyspace<\/a><\/p>\n<p><a href=\"myspace.com\/estricalla\">myspace.com\/estricalla<\/a><\/p>\n<p><a href=\"www.mostros.info\">www.mostros.info<\/a><\/p>\n<p><a href=\"www.humilitate.bandcamp.com\">www.humilitate.bandcamp.com<\/a><\/p>\n<p><a href=\"http:\/\/www.kklrd.com\">www.kklrd.com<\/a><\/p>\n<p><a href=\"%20www.bonberenea.com\">www.bonberenea.com<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Ya esta en la calle KKLRD!! el trabajo es fruto de la colaboracion de diferentes artistas: ZINC, ESTRICALLA, HUMILITATE, MOSTROS, JOSEVISKY y BONBERENEA EKINTZAK. Mezcla de musica y el arte del comic. Una cancion inedita por cada banda en formato [&hellip;]<\/p>\n","protected":false},"featured_media":1768,"template":"","meta":{"_exactmetrics_skip_tracking":false},"product_cat":[476],"product_tag":[456,442,205,458],"_links":{"self":[{"href":"https:\/\/www.bonberenea.com\/es\/wp-json\/wp\/v2\/product\/4414"}],"collection":[{"href":"https:\/\/www.bonberenea.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.bonberenea.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bonberenea.com\/es\/wp-json\/wp\/v2\/media\/1768"}],"wp:attachment":[{"href":"https:\/\/www.bonberenea.com\/es\/wp-json\/wp\/v2\/media?parent=4414"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.bonberenea.com\/es\/wp-json\/wp\/v2\/product_cat?post=4414"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.bonberenea.com\/es\/wp-json\/wp\/v2\/product_tag?post=4414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}