{"id":40129,"date":"2026-03-19T18:47:44","date_gmt":"2026-03-19T17:47:44","guid":{"rendered":"https:\/\/www.bonberenea.com\/?p=40129"},"modified":"2026-03-19T18:47:44","modified_gmt":"2026-03-19T17:47:44","slug":"lovenjoy-kiev-2","status":"publish","type":"post","link":"https:\/\/www.bonberenea.com\/es\/blog\/lovenjoy-kiev-2\/","title":{"rendered":"Love\u00b4N\u00b4Joy (Kiev)"},"content":{"rendered":"<p>El d\u00eda 26 de Abril a las 20:00h actuara en Bonberenea Love\u00b4N\u00b4Joy (Kiev)<br \/>\nEntrada 10\u20ac<\/p>","protected":false},"excerpt":{"rendered":"<p>El d\u00eda 26 de Abril a las 20:00h actuara en Bonberenea Love\u00b4N\u00b4Joy (Kiev) Entrada 10\u20ac<\/p>\n","protected":false},"author":5,"featured_media":40130,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"categories":[1,11],"tags":[],"_links":{"self":[{"href":"https:\/\/www.bonberenea.com\/es\/wp-json\/wp\/v2\/posts\/40129"}],"collection":[{"href":"https:\/\/www.bonberenea.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bonberenea.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bonberenea.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bonberenea.com\/es\/wp-json\/wp\/v2\/comments?post=40129"}],"version-history":[{"count":1,"href":"https:\/\/www.bonberenea.com\/es\/wp-json\/wp\/v2\/posts\/40129\/revisions"}],"predecessor-version":[{"id":40131,"href":"https:\/\/www.bonberenea.com\/es\/wp-json\/wp\/v2\/posts\/40129\/revisions\/40131"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bonberenea.com\/es\/wp-json\/wp\/v2\/media\/40130"}],"wp:attachment":[{"href":"https:\/\/www.bonberenea.com\/es\/wp-json\/wp\/v2\/media?parent=40129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bonberenea.com\/es\/wp-json\/wp\/v2\/categories?post=40129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bonberenea.com\/es\/wp-json\/wp\/v2\/tags?post=40129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}